{"id":41,"count":2,"description":"","link":"https:\/\/technischeredaktion.com\/multimediaprojekte\/tag\/serious-games\/","name":"Serious Games","slug":"serious-games","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/technischeredaktion.com\/multimediaprojekte\/wp-json\/wp\/v2\/tags\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/technischeredaktion.com\/multimediaprojekte\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/technischeredaktion.com\/multimediaprojekte\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/technischeredaktion.com\/multimediaprojekte\/wp-json\/wp\/v2\/posts?tags=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}